{"id":3731,"date":"2022-07-15T09:22:12","date_gmt":"2022-07-15T09:22:12","guid":{"rendered":"https:\/\/ruminteriors.com\/projectes\/reforma-duna-planta-unificant-espais\/"},"modified":"2022-08-31T16:35:09","modified_gmt":"2022-08-31T16:35:09","slug":"reforma-duna-planta-unificant-espais","status":"publish","type":"projectes","link":"https:\/\/ruminteriors.com\/es\/proyectos\/reforma-duna-planta-unificant-espais\/","title":{"rendered":"Reforma de una planta: unificando espacios"},"content":{"rendered":"\n<p>En la primera planta de esta casa, se hizo un buen cambio para adecuarlo a la actual funcionalidad de este matrimonio.<\/p>\n\n\n\n<p>Anteriormente, ten\u00edamos dos habitaciones y un ba\u00f1o, todo separado por un pasillo, lo que se quer\u00eda conseguir era unificar todos los espacios en uno, dejando sitio a una zona amplia de vestuario, el dormitorio principal con el ba\u00f1o suite y porque no un espacio donde poder tocar el piano.<\/p>\n\n\n\n<p>Jugando con la combinaci\u00f3n del blanco y el roble hemos querido obtener un ambiente amplio y neutro, una zona de la casa en la que relajarte y estar c\u00f3modo. Los materiales utilizados son principalmente laca blanca y roble natural. Deseamos destacar los tiradores de los armarios, hechos a medida y de roble natural. El papel pintado del cabezal de la cama, las mesitas y la iluminaci\u00f3n nos han ayudado a dar ese ambiente c\u00e1lido y neutro que busc\u00e1bamos, sin descuidarnos la escalera donde hemos querido destacar la barandilla de roble hecha a medida que nos ilumina todos los escalones.<\/p>\n\n\n\n<p>En el ba\u00f1o, hemos seguido con la l\u00ednea del blanco y el roble, pero d\u00e1ndole un toque especial con los azulejos dibujados del pavimento.<\/p>\n\n\n\n<p>Ha sido un placer realizar esta reforma. Cost\u00f3 empezar&#8230; pero creo que ha habido muy buena sinton\u00eda con los clientes. Contenta haber hecho una nueva amistad con nuevos clientes.<\/p>\n","protected":false},"featured_media":2956,"template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"categoria-projectes":[29],"class_list":["post-3731","projectes","type-projectes","status-publish","has-post-thumbnail","hentry","categoria-projectes-diseno-de-mobiliario"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Reforma de una planta: unificando espacios - Ruminteriors<\/title>\n<meta name=\"description\" content=\"En la primera planta de esta casa, se hizo un buen cambio para adecuarlo a la actual funcionalidad de este matrimonio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ruminteriors.com\/es\/proyectos\/reforma-duna-planta-unificant-espais\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reforma de una planta: unificando espacios - Ruminteriors\" \/>\n<meta property=\"og:description\" content=\"En la primera planta de esta casa, se hizo un buen cambio para adecuarlo a la actual funcionalidad de este matrimonio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ruminteriors.com\/es\/proyectos\/reforma-duna-planta-unificant-espais\/\" \/>\n<meta property=\"og:site_name\" content=\"Ruminteriors\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-31T16:35:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ruminteriors.com\/wp-content\/uploads\/2022\/07\/1ruminteriors-reforma-dormitori.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1591\" \/>\n\t<meta property=\"og:image:height\" content=\"1061\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ruminteriors.com\/es\/proyectos\/reforma-duna-planta-unificant-espais\/\",\"url\":\"https:\/\/ruminteriors.com\/es\/proyectos\/reforma-duna-planta-unificant-espais\/\",\"name\":\"Reforma de una planta: unificando espacios - Ruminteriors\",\"isPartOf\":{\"@id\":\"https:\/\/ruminteriors.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ruminteriors.com\/es\/proyectos\/reforma-duna-planta-unificant-espais\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ruminteriors.com\/es\/proyectos\/reforma-duna-planta-unificant-espais\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ruminteriors.com\/wp-content\/uploads\/2022\/07\/1ruminteriors-reforma-dormitori.jpg\",\"datePublished\":\"2022-07-15T09:22:12+00:00\",\"dateModified\":\"2022-08-31T16:35:09+00:00\",\"description\":\"En la primera planta de esta casa, se hizo un buen cambio para adecuarlo a la actual funcionalidad de este matrimonio.\",\"breadcrumb\":{\"@id\":\"https:\/\/ruminteriors.com\/es\/proyectos\/reforma-duna-planta-unificant-espais\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ruminteriors.com\/es\/proyectos\/reforma-duna-planta-unificant-espais\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/ruminteriors.com\/es\/proyectos\/reforma-duna-planta-unificant-espais\/#primaryimage\",\"url\":\"https:\/\/ruminteriors.com\/wp-content\/uploads\/2022\/07\/1ruminteriors-reforma-dormitori.jpg\",\"contentUrl\":\"https:\/\/ruminteriors.com\/wp-content\/uploads\/2022\/07\/1ruminteriors-reforma-dormitori.jpg\",\"width\":1591,\"height\":1061},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ruminteriors.com\/es\/proyectos\/reforma-duna-planta-unificant-espais\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ruminteriors.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projectes\",\"item\":\"https:\/\/ruminteriors.com\/projectes\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Reforma de una planta: unificando espacios\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ruminteriors.com\/#website\",\"url\":\"https:\/\/ruminteriors.com\/\",\"name\":\"Ruminteriors\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ruminteriors.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reforma de una planta: unificando espacios - Ruminteriors","description":"En la primera planta de esta casa, se hizo un buen cambio para adecuarlo a la actual funcionalidad de este matrimonio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ruminteriors.com\/es\/proyectos\/reforma-duna-planta-unificant-espais\/","og_locale":"es_ES","og_type":"article","og_title":"Reforma de una planta: unificando espacios - Ruminteriors","og_description":"En la primera planta de esta casa, se hizo un buen cambio para adecuarlo a la actual funcionalidad de este matrimonio.","og_url":"https:\/\/ruminteriors.com\/es\/proyectos\/reforma-duna-planta-unificant-espais\/","og_site_name":"Ruminteriors","article_modified_time":"2022-08-31T16:35:09+00:00","og_image":[{"width":1591,"height":1061,"url":"https:\/\/ruminteriors.com\/wp-content\/uploads\/2022\/07\/1ruminteriors-reforma-dormitori.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ruminteriors.com\/es\/proyectos\/reforma-duna-planta-unificant-espais\/","url":"https:\/\/ruminteriors.com\/es\/proyectos\/reforma-duna-planta-unificant-espais\/","name":"Reforma de una planta: unificando espacios - Ruminteriors","isPartOf":{"@id":"https:\/\/ruminteriors.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ruminteriors.com\/es\/proyectos\/reforma-duna-planta-unificant-espais\/#primaryimage"},"image":{"@id":"https:\/\/ruminteriors.com\/es\/proyectos\/reforma-duna-planta-unificant-espais\/#primaryimage"},"thumbnailUrl":"https:\/\/ruminteriors.com\/wp-content\/uploads\/2022\/07\/1ruminteriors-reforma-dormitori.jpg","datePublished":"2022-07-15T09:22:12+00:00","dateModified":"2022-08-31T16:35:09+00:00","description":"En la primera planta de esta casa, se hizo un buen cambio para adecuarlo a la actual funcionalidad de este matrimonio.","breadcrumb":{"@id":"https:\/\/ruminteriors.com\/es\/proyectos\/reforma-duna-planta-unificant-espais\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ruminteriors.com\/es\/proyectos\/reforma-duna-planta-unificant-espais\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ruminteriors.com\/es\/proyectos\/reforma-duna-planta-unificant-espais\/#primaryimage","url":"https:\/\/ruminteriors.com\/wp-content\/uploads\/2022\/07\/1ruminteriors-reforma-dormitori.jpg","contentUrl":"https:\/\/ruminteriors.com\/wp-content\/uploads\/2022\/07\/1ruminteriors-reforma-dormitori.jpg","width":1591,"height":1061},{"@type":"BreadcrumbList","@id":"https:\/\/ruminteriors.com\/es\/proyectos\/reforma-duna-planta-unificant-espais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ruminteriors.com\/"},{"@type":"ListItem","position":2,"name":"Projectes","item":"https:\/\/ruminteriors.com\/projectes\/"},{"@type":"ListItem","position":3,"name":"Reforma de una planta: unificando espacios"}]},{"@type":"WebSite","@id":"https:\/\/ruminteriors.com\/#website","url":"https:\/\/ruminteriors.com\/","name":"Ruminteriors","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ruminteriors.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/ruminteriors.com\/es\/wp-json\/wp\/v2\/projectes\/3731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ruminteriors.com\/es\/wp-json\/wp\/v2\/projectes"}],"about":[{"href":"https:\/\/ruminteriors.com\/es\/wp-json\/wp\/v2\/types\/projectes"}],"version-history":[{"count":0,"href":"https:\/\/ruminteriors.com\/es\/wp-json\/wp\/v2\/projectes\/3731\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ruminteriors.com\/es\/wp-json\/wp\/v2\/media\/2956"}],"wp:attachment":[{"href":"https:\/\/ruminteriors.com\/es\/wp-json\/wp\/v2\/media?parent=3731"}],"wp:term":[{"taxonomy":"categoria-projectes","embeddable":true,"href":"https:\/\/ruminteriors.com\/es\/wp-json\/wp\/v2\/categoria-projectes?post=3731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}